{"id":52563,"date":"2025-10-23T14:54:40","date_gmt":"2025-10-23T12:54:40","guid":{"rendered":"https:\/\/symetrie.fr\/?page_id=52563"},"modified":"2026-02-12T15:03:32","modified_gmt":"2026-02-12T14:03:32","slug":"non-magnetic-hexapods","status":"publish","type":"page","link":"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/","title":{"rendered":"Non-magnetic hexapod"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;36406&#8243; bg_position=&#8221;center bottom&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;bgg page-titre-full&#8221; color_overlay=&#8221;rgba(0,0,0,0.72)&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fixed&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; el_class=&#8221;titre-page&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;480&#8243;][vc_column_text css=&#8221;&#8221; el_class=&#8221;titre&#8221; text_direction=&#8221;default&#8221;]\n<h1>Non-magnetic hexapod<\/h1>\n<h2>Our hexapods with stable or zero magnetic fields<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;breadcrumbs&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;15&#8243;][vc_column_text]<span><span><a href=\"https:\/\/symetrie.fr\/en\/\">Home<\/a><\/span><\/span>[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;15&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2 style=\"margin-top: 0pt; margin-bottom: 8pt; font-family: Arial; font-size: 12pt; text-align: center;\">They choose Sym\u00e9trie<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\t\n\t\t<div id=\"gs_logo_area_33\" data-sort=\"name\" data-shortcode-id=\"33\" class=\"gs_logo_area gs_logo_area_33 slider1 \" data-options='{\"logo_per_page\":\"6\"}' style=\"opacity: 0; visibility: hidden;\">\n\t\t\t<div class=\"gs_logo_area--inner\">\n\n\t\t\t\t<!-- Category Filters - New (Global) -->\n\t\t\t\t\t\n\t\t\t\t\n<div class=\"gs_logo_container gs_carousel_swiper gs_logo_fix_height_and_center\" data-carousel-config='{\"direction\":\"horizontal\",\"speed\":1500,\"isAutoplay\":true,\"autoplayDelay\":0,\"loop\":true,\"pauseOnHover\":false,\"ticker\":false,\"navs\":false,\"navs_pos\":\"bottom\",\"dots\":false,\"dynamic_dots\":true,\"slideSpace\":10,\"slidesPerGroup\":1,\"desktopLogos\":8,\"tabletLogos\":3,\"mobileLogos\":3,\"reverseDirection\":false}'>\n\n\t\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"28\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRezfEFFichier-1-scaled.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"NORTHROP GRUMMAN\" title=\"NORTHROP GRUMMAN\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRezfEFFichier-1-scaled.webp 2560w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRezfEFFichier-1-500x111.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRezfEFFichier-1-1536x341.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRezfEFFichier-1-768x170.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRezfEFFichier-1-2048x454.webp 2048w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"24\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/airbus.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"airbus\" title=\"AIRBUS\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/airbus.webp 1245w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/airbus-500x93.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/airbus-768x142.webp 768w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"25\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/air-liquide.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"air liquide\" title=\"AIR LIQUIDE\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/air-liquide.webp 2006w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/air-liquide-500x96.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/air-liquide-1536x295.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/air-liquide-768x147.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/air-liquide-1870x385.webp 1870w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"110\" height=\"96\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/Ball-AerospaceFichier-1.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"Ball Aerospace\" title=\"BALL\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/Ball-AerospaceFichier-1.webp 541w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/Ball-AerospaceFichier-1-427x372.webp 427w\" sizes=\"auto, (max-width: 110px) 100vw, 110px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"27\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/stellantis.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"stellantis\" title=\"STELLANTIS\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/stellantis.webp 2051w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/stellantis-500x106.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/stellantis-1536x325.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/stellantis-768x163.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/stellantis-2048x433.webp 2048w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"96\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/1Fichier-1.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"NVIDIA\" title=\"NVIDIA\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"43\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2022\/01\/R-1-e1763480645714.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"GOOGLE\" title=\"Google\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"43\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/dassault.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"Dassault Aviation\" title=\"DASSAULT AVIATION\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/dassault.webp 2281w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/dassault-500x167.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/dassault-1536x512.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/dassault-768x256.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/dassault-2048x683.webp 2048w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"36\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/Ball-fDf1gfggVDDDFFichier-1.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"ASML\" title=\"ASML\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"72\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/zeiss-logo-rgb_2023.png\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"CARL ZEISS\" title=\"ZEISS\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/zeiss-logo-rgb_2023.png 1182w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/zeiss-logo-rgb_2023-500x281.png 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/zeiss-logo-rgb_2023-768x432.png 768w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"96\" height=\"96\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2022\/01\/Robert-Bosch.jpg\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"Robert Bosch\" title=\"Bosch\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2022\/01\/Robert-Bosch.jpg 372w, https:\/\/symetrie.fr\/wp-content\/uploads\/2022\/01\/Robert-Bosch-100x100.jpg 100w, https:\/\/symetrie.fr\/wp-content\/uploads\/2022\/01\/Robert-Bosch-140x140.jpg 140w, https:\/\/symetrie.fr\/wp-content\/uploads\/2022\/01\/Robert-Bosch-350x350.jpg 350w\" sizes=\"auto, (max-width: 96px) 100vw, 96px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"20\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/bae-systems.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"bae systems\" title=\"BAE SYSTEM\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/bae-systems.webp 1985w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/bae-systems-500x78.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/bae-systems-1536x238.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/bae-systems-768x119.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/bae-systems-1870x308.webp 1870w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"28\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/1Fichier-2.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"HUAWEI\" title=\"HUAWEI\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"41\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/GEFichier-1-1-scaled.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"SAAB\" title=\"SAAB\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/GEFichier-1-1-scaled.webp 2560w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/GEFichier-1-1-500x159.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/GEFichier-1-1-1536x489.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/GEFichier-1-1-768x245.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/GEFichier-1-1-2048x652.webp 2048w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"38\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRgERGhteFichier-1.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"KNDS DEFENCE\" title=\"KNDS\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRgERGhteFichier-1.webp 2363w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRgERGhteFichier-1-500x147.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRgERGhteFichier-1-1536x451.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRgERGhteFichier-1-768x226.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/FRgERGhteFichier-1-2048x601.webp 2048w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"44\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/APPL-scaled.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"APPLE\" title=\"APPLE\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/APPL-scaled.webp 2560w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/APPL-500x171.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/APPL-1536x525.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/APPL-768x263.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/APPL-2048x701.webp 2048w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\n\t\t\t<div class=\"gs_logo_single--wrapper\">\n\t\t\t\t<div class=\"gs_logo_single\">\n\n\t\t\t\t\t<!-- Logo Img -->\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"27\" src=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/l3harris.webp\" class=\"tt-placement-top tt-bgcolor-one-%23ff5f6d tt-bgcolor-two-%23ffc371 tt-textcolor-%23fff gs-logo--img wp-post-image\" alt=\"l3harris\" title=\"L3 HARRIS\" srcset=\"https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/l3harris.webp 2084w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/l3harris-500x107.webp 500w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/l3harris-1536x329.webp 1536w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/l3harris-768x165.webp 768w, https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/03\/l3harris-2048x439.webp 2048w\" sizes=\"auto, (max-width: 128px) 100vw, 128px\" \/>\n\t\t\t\t\t<!-- Logo Title -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<!-- Logo Category -->\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\n\t\n<\/div>\n\t\t\t\t<!-- Pagination -->\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\n\t\t<style>#gs_logo_area_33:not(.verticaltickerdown):not(.verticalticker) .gs_logo_container{margin-left:-5px}#gs_logo_area_33:not(.verticaltickerdown):not(.verticalticker) .gs_logo_container{margin-right:-5px}#gs_logo_area_33:not(.verticaltickerdown):not(.verticalticker) .gs_logo_single--wrapper{padding:5px}#gs_logo_area_33 ul.gs-logo-filter-cats{text-align:center!important}#gs_logo_area_33 .gs_logo_single--wrapper{width:12.5%}@media (max-width:1023px){#gs_logo_area_33 .gs_logo_single--wrapper{width:33.333333333333%}}@media (max-width:767px){#gs_logo_area_33 .gs_logo_single--wrapper{width:33.333333333333%}}<\/style>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2 style=\"margin-top: 0pt; margin-bottom: 8pt; font-family: Arial; font-size: 12pt; text-align: center;\">Non-magnetic hexapods for magnetic field-sensitive environments<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3>High-precision positioning without magnetic interference<\/h3>\n<p>Some <strong>scientific research, quantum physics, and experimental applications<\/strong> require completely non-magnetic positioning systems in order to avoid any disturbance of magnetic fields or interference with <strong>sensitive measuring instruments<\/strong> (SQUID sensors, magnetic resonance, magnetic imaging, etc.).<\/p>\n<p>Sym\u00e9trie&#8217;s non-magnetic hexapods are specially developed for these critical environments. Their design ensures <strong>operation without electromagnetic interaction<\/strong>, while maintaining the <strong>mechanical rigidity and sub-micron positioning accuracy<\/strong> characteristic of Sym\u00e9trie systems.<\/p>\n<h3>Non-magnetic design and optimized architecture<\/h3>\n<p>Each non-magnetic hexapod is designed using materials carefully selected for their <strong>lack of ferromagnetic properties and dimensional stability<\/strong>:<\/p>\n<ul>\n<li><strong>Non-magnetic aluminum alloys, titanium, or bronze<\/strong>, depending on mechanical and thermal constraints.<\/li>\n<li><strong>Screws, pins, and guide elements<\/strong> made of non-magnetic austenitic steel or technical ceramics.<\/li>\n<li><strong>Non-magnetic motors<\/strong> (piezoelectric motors, direct-drive linear actuators, or special actuators).<\/li>\n<li><strong>Absolute linear encoders<\/strong> guaranteeing <strong>precise position feedback<\/strong> without magnetic sensors.<\/li>\n<li><strong>Ultra-flat &#8220;hexaglide&#8221; architecture<\/strong>, ensuring <strong>stable and rigid kinematics<\/strong> while minimizing the overall height of the system\u2014an advantage for integration in vacuum chambers or between superconducting magnet poles.<\/li>\n<\/ul>\n<p>The absence of ferromagnetic components ensures <strong>neutral behavior with respect to static and variable fields<\/strong>, which is essential for sensitive research environments.[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;10&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2 style=\"margin-top: 0pt; margin-bottom: 8pt; font-family: Arial; font-size: 12pt; text-align: center;\">One of our non-magnetic projects<\/h2>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;projets&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][fancy_box box_style=&#8221;default&#8221; icon_family=&#8221;none&#8221; image_url=&#8221;36400&#8243; color=&#8221;accent-color&#8221; border_radius=&#8221;default&#8221; image_loading=&#8221;default&#8221; link_url=&#8221;https:\/\/symetrie.fr\/en\/applications\/research-and-engineering\/non-magnetic-hexapod\/&#8221; min_height=&#8221;200&#8243;][\/fancy_box][vc_column_text]\n<h3 style=\"text-align: center;\"><a href=\"https:\/\/symetrie.fr\/en\/applications\/research-and-engineering\/non-magnetic-hexapod\/\">Non-magnetic hexapod<\/a><\/h3>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][nectar_btn size=&#8221;large&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-3&#8243; icon_family=&#8221;none&#8221; url=&#8221;https:\/\/symetrie.fr\/en\/applications\/research-and-engineering\/non-magnetic-hexapod\/&#8221; text=&#8221;See the project&#8221; margin_top=&#8221;0&#8243; margin_right=&#8221;auto&#8221; margin_bottom=&#8221;0&#8243; margin_left=&#8221;auto&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; animation_easing=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2 style=\"margin-top: 0pt; margin-bottom: 8pt; font-family: Arial; font-size: 12pt; text-align: center;\">Why choose a SYMETRIE hexapod?<\/h2>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: left;\" data-start=\"213\" data-end=\"447\">25 years of recognized experience<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: left;\" data-start=\"213\" data-end=\"447\">Unique know-how in the design and manufacture of hexapods, the fruit of multidisciplinary expertise (mechatronics, robotics, on-board electronics, control and command, software, etc.).<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: left;\" data-start=\"449\" data-end=\"605\">A team of expert engineers<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: left;\" data-start=\"449\" data-end=\"605\">Specialists who combine mechanical precision, technological innovation and a global vision of customer needs.<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: left;\" data-start=\"607\" data-end=\"647\">Hexapods built to last<\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: left;\">&#8211; Optimized design for enhanced performance<\/p>\n<p style=\"text-align: left;\">&#8211; Rigorous manufacturing for impeccable quality<\/p>\n<p style=\"text-align: left;\">&#8211; Rigorous quality control at every stage of the robot production process<\/p>\n[\/vc_column_text][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;20&#8243;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: left;\"><strong data-start=\"807\" data-end=\"835\">Tailor-made solutions<\/strong><\/h3>\n[\/vc_column_text][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<p style=\"text-align: left;\" data-start=\"804\" data-end=\"908\">Thanks to its evolutionary technology, our hexapods are: reliable, robust and adapted to the most complex environments.<\/p>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#F4F4F4&#8243; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; bottom_padding=&#8221;50&#8243; left_padding_desktop=&#8221;200&#8243; right_padding_desktop=&#8221;200&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][image_with_animation image_url=&#8221;42779&#8243; image_size=&#8221;full&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;3\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css=&#8221;&#8221; text_direction=&#8221;default&#8221;]\n<h2>Contact an expert :<\/h2>\n<p>Submit a form and receive a quick response by e-mail or telephone from one of our sales engineers.<\/p>\n[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; desktop_text_alignment=&#8221;center&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/5&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][nectar_btn size=&#8221;small&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Accent-Color&#8221; color_override=&#8221;#0033A0&#8243; icon_family=&#8221;none&#8221; text=&#8221;Contact an expert&#8221; url=&#8221;https:\/\/symetrie.fr\/en\/contact\/&#8221; margin_right=&#8221;30&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;53353&#8243; bg_position=&#8221;center center&#8221; background_image_loading=&#8221;skip-lazy-load&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;50&#8243; constrain_group_1=&#8221;yes&#8221; bottom_padding=&#8221;50&#8243; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; id=&#8221;catalogue&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;53710&#8243; image_size=&#8221;custom&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;100%&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;None&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; custom_image_size=&#8221;407&#215;304&#8243;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;left&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_padding_type=&#8221;default&#8221; gradient_type=&#8221;default&#8221;][vc_column_text css_animation=&#8221;fadeInUp&#8221; css=&#8221;.vc_custom_1770904394943{margin-top: 20px !important;margin-bottom: 40px !important;}&#8221; el_class=&#8221;blanc&#8221; text_direction=&#8221;default&#8221;]\n<h3 style=\"text-align: left;\">Discover the most efficient hexapod solutions<\/h3>\n[\/vc_column_text][nectar_btn size=&#8221;jumbo&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-2&#8243; icon_family=&#8221;none&#8221; el_class=&#8221;blanc&#8221; url=&#8221;https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/10\/WEB_SYMETRIE_Positioning_Catalog_2025_301025.pdf&#8221; text=&#8221;Our positioning hexapods&#8221; margin_bottom=&#8221;20&#8243; css_animation=&#8221;fadeInRight&#8221; margin_right=&#8221;15&#8243;][nectar_btn size=&#8221;jumbo&#8221; open_new_tab=&#8221;true&#8221; button_style=&#8221;regular&#8221; button_color_2=&#8221;Extra-Color-2&#8243; icon_family=&#8221;none&#8221; el_class=&#8221;blanc&#8221; url=&#8221;https:\/\/symetrie.fr\/wp-content\/uploads\/2025\/04\/Motion_Catalog_2025.pdf&#8221; text=&#8221;Our motion hexapods&#8221; margin_bottom=&#8221;30&#8243; css_animation=&#8221;fadeInRight&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/6&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_image=&#8221;36406&#8243; bg_position=&#8221;center bottom&#8221; background_image_loading=&#8221;default&#8221; bg_repeat=&#8221;no-repeat&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;80&#8243; text_color=&#8221;light&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; class=&#8221;bgg page-titre-full&#8221; color_overlay=&#8221;rgba(0,0,0,0.72)&#8221; overlay_strength=&#8221;0.5&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; parallax_bg=&#8221;true&#8221; parallax_bg_speed=&#8221;fixed&#8221; shape_type=&#8221;&#8221; gradient_type=&#8221;default&#8221;][vc_column&#8230;<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"page-category":[],"class_list":["post-52563","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Our non-magnetic hexapods<\/title>\n<meta name=\"description\" content=\"Discover our non-magnetic hexapods for research, quantum physics and experimental physics. They avoid any magnetic disturbance\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Our non-magnetic hexapods\" \/>\n<meta property=\"og:description\" content=\"Discover our non-magnetic hexapods for research, quantum physics and experimental physics. They avoid any magnetic disturbance\" \/>\n<meta property=\"og:url\" content=\"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/\" \/>\n<meta property=\"og:site_name\" content=\"Sym\u00e9trie\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/symetriehexapods\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-12T14:03:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@SYMETRIE\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/non-magnetic-hexapods\\\/\",\"url\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/non-magnetic-hexapods\\\/\",\"name\":\"Our non-magnetic hexapods\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/#website\"},\"datePublished\":\"2025-10-23T12:54:40+00:00\",\"dateModified\":\"2026-02-12T14:03:32+00:00\",\"description\":\"Discover our non-magnetic hexapods for research, quantum physics and experimental physics. They avoid any magnetic disturbance\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/non-magnetic-hexapods\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/symetrie.fr\\\/en\\\/non-magnetic-hexapods\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/non-magnetic-hexapods\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non-magnetic hexapod\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/\",\"name\":\"Sym\u00e9trie\",\"description\":\"Expert mondial en hexapodes de positionnement de pr\u00e9cision depuis plus de 25 ans\",\"publisher\":{\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/#organization\",\"name\":\"Sym\u00e9trie\",\"url\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/symetrie.fr\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/SYMETRIE-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/symetrie.fr\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/SYMETRIE-logo.jpg\",\"width\":1708,\"height\":357,\"caption\":\"Sym\u00e9trie\"},\"image\":{\"@id\":\"https:\\\/\\\/symetrie.fr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/symetriehexapods\\\/\",\"https:\\\/\\\/x.com\\\/SYMETRIE\",\"https:\\\/\\\/www.instagram.com\\\/symetrie_hexapods\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/symetrie\",\"https:\\\/\\\/fr.pinterest.com\\\/symetriehexapod\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/SYMETRIEnimes\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our non-magnetic hexapods","description":"Discover our non-magnetic hexapods for research, quantum physics and experimental physics. They avoid any magnetic disturbance","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/","og_locale":"en_US","og_type":"article","og_title":"Our non-magnetic hexapods","og_description":"Discover our non-magnetic hexapods for research, quantum physics and experimental physics. They avoid any magnetic disturbance","og_url":"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/","og_site_name":"Sym\u00e9trie","article_publisher":"https:\/\/www.facebook.com\/symetriehexapods\/","article_modified_time":"2026-02-12T14:03:32+00:00","twitter_card":"summary_large_image","twitter_site":"@SYMETRIE","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/","url":"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/","name":"Our non-magnetic hexapods","isPartOf":{"@id":"https:\/\/symetrie.fr\/en\/#website"},"datePublished":"2025-10-23T12:54:40+00:00","dateModified":"2026-02-12T14:03:32+00:00","description":"Discover our non-magnetic hexapods for research, quantum physics and experimental physics. They avoid any magnetic disturbance","breadcrumb":{"@id":"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/symetrie.fr\/en\/non-magnetic-hexapods\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/symetrie.fr\/en\/"},{"@type":"ListItem","position":2,"name":"Non-magnetic hexapod"}]},{"@type":"WebSite","@id":"https:\/\/symetrie.fr\/en\/#website","url":"https:\/\/symetrie.fr\/en\/","name":"Sym\u00e9trie","description":"Expert mondial en hexapodes de positionnement de pr\u00e9cision depuis plus de 25 ans","publisher":{"@id":"https:\/\/symetrie.fr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/symetrie.fr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/symetrie.fr\/en\/#organization","name":"Sym\u00e9trie","url":"https:\/\/symetrie.fr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/symetrie.fr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/symetrie.fr\/wp-content\/uploads\/2017\/12\/SYMETRIE-logo.jpg","contentUrl":"https:\/\/symetrie.fr\/wp-content\/uploads\/2017\/12\/SYMETRIE-logo.jpg","width":1708,"height":357,"caption":"Sym\u00e9trie"},"image":{"@id":"https:\/\/symetrie.fr\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/symetriehexapods\/","https:\/\/x.com\/SYMETRIE","https:\/\/www.instagram.com\/symetrie_hexapods\/","https:\/\/www.linkedin.com\/company\/symetrie","https:\/\/fr.pinterest.com\/symetriehexapod\/","https:\/\/www.youtube.com\/user\/SYMETRIEnimes"]}]}},"_links":{"self":[{"href":"https:\/\/symetrie.fr\/en\/wp-json\/wp\/v2\/pages\/52563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/symetrie.fr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/symetrie.fr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/symetrie.fr\/en\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/symetrie.fr\/en\/wp-json\/wp\/v2\/comments?post=52563"}],"version-history":[{"count":0,"href":"https:\/\/symetrie.fr\/en\/wp-json\/wp\/v2\/pages\/52563\/revisions"}],"wp:attachment":[{"href":"https:\/\/symetrie.fr\/en\/wp-json\/wp\/v2\/media?parent=52563"}],"wp:term":[{"taxonomy":"page-category","embeddable":true,"href":"https:\/\/symetrie.fr\/en\/wp-json\/wp\/v2\/page-category?post=52563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}